{"id":20215757,"date":"2023-07-03T15:34:56","date_gmt":"2023-07-03T13:34:56","guid":{"rendered":"https:\/\/javataste.de\/?post_type=product&#038;p=20215757"},"modified":"2026-04-21T19:57:57","modified_gmt":"2026-04-21T17:57:57","slug":"poci-teh-melati-indonesischer-jasmintee-25x2g","status":"publish","type":"product","link":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/","title":{"rendered":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g"},"content":{"rendered":"<p style=\"text-align: left;\">Teh Poci &#8211; Der urspr\u00fcngliche Teeduft Genuss von dem einheimischen indonesischen Tee, Blatttee wird auserlesen verarbeitet ergibt ein unverwechselbares Aroma.<\/p>","protected":false},"excerpt":{"rendered":"<p>Zutaten: Jasmintee<\/p>\n<p>mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.<\/p>","protected":false},"featured_media":20215758,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[75],"product_tag":[284,285,298],"class_list":["post-20215757","product","type-product","status-publish","has-post-thumbnail","product_cat-getraenke","product_tag-teh","product_tag-jasmintee","product_tag-teh-poci","first","outofstock","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\n\t\t<meta name=\"google-site-verification\" content=\"rocBGGVHEbDaOVhf0vvAL9LjfJvr9FmbtsSHXel4X2U\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"JaVaTaste Online Shop - Indonesischer Online Shop\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop\" \/>\n\t\t<meta property=\"og:description\" content=\"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-03T13:34:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-21T17:57:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/javataste.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/javataste.de\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/produkt-kategorie\\\/getraenke\\\/#listItem\",\"name\":\"Getr\\u00e4nke\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/produkt-kategorie\\\/getraenke\\\/#listItem\",\"position\":3,\"name\":\"Getr\\u00e4nke\",\"item\":\"https:\\\/\\\/javataste.de\\\/en\\\/produkt-kategorie\\\/getraenke\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#listItem\",\"name\":\"Poci Teh Melati \\u2014 indonesischer Jasmintee 25x2g\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#listItem\",\"position\":4,\"name\":\"Poci Teh Melati \\u2014 indonesischer Jasmintee 25x2g\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/produkt-kategorie\\\/getraenke\\\/#listItem\",\"name\":\"Getr\\u00e4nke\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#itempage\",\"url\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/\",\"name\":\"Poci Teh Melati \\u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop\",\"description\":\"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/javataste.de\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/AF751E89-9E4B-4FC9-9FB9-79393FA3E13E.jpeg\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#mainImage\",\"width\":623,\"height\":271},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/product\\\/poci-teh-melati-indonesischer-jasmintee-25x2g\\\/#mainImage\"},\"datePublished\":\"2023-07-03T15:34:56+02:00\",\"dateModified\":\"2026-04-21T19:57:57+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/#organization\",\"name\":\"JaVaTaste Online Shop\",\"description\":\"Indonesischer Online Shop\",\"url\":\"https:\\\/\\\/javataste.de\\\/en\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/javataste.de\\\/en\\\/\",\"name\":\"JaVaTaste Online Shop\",\"description\":\"Indonesischer Online Shop\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/javataste.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop","description":"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.","canonical_url":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;meta name=\"google-site-verification\" content=\"rocBGGVHEbDaOVhf0vvAL9LjfJvr9FmbtsSHXel4X2U\" \/&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/javataste.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/javataste.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/javataste.de\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/#listItem","name":"Getr\u00e4nke"},"previousItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/#listItem","position":3,"name":"Getr\u00e4nke","item":"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/","nextItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#listItem","name":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g"},"previousItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#listItem","position":4,"name":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g","previousItem":{"@type":"ListItem","@id":"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/#listItem","name":"Getr\u00e4nke"}}]},{"@type":"ItemPage","@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#itempage","url":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/","name":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop","description":"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/javataste.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/javataste.de\/wp-content\/uploads\/2023\/07\/AF751E89-9E4B-4FC9-9FB9-79393FA3E13E.jpeg","@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#mainImage","width":623,"height":271},"primaryImageOfPage":{"@id":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/#mainImage"},"datePublished":"2023-07-03T15:34:56+02:00","dateModified":"2026-04-21T19:57:57+02:00"},{"@type":"Organization","@id":"https:\/\/javataste.de\/en\/#organization","name":"JaVaTaste Online Shop","description":"Indonesischer Online Shop","url":"https:\/\/javataste.de\/en\/"},{"@type":"WebSite","@id":"https:\/\/javataste.de\/en\/#website","url":"https:\/\/javataste.de\/en\/","name":"JaVaTaste Online Shop","description":"Indonesischer Online Shop","inLanguage":"en-GB","publisher":{"@id":"https:\/\/javataste.de\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"JaVaTaste Online Shop - Indonesischer Online Shop","og:type":"article","og:title":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop","og:description":"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren.","og:url":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/","article:published_time":"2023-07-03T13:34:56+00:00","article:modified_time":"2026-04-21T17:57:57+00:00","twitter:card":"summary_large_image","twitter:title":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g - JaVaTaste Online Shop","twitter:description":"Zutaten: Jasmintee mit indonesischen frischen Geschmack und extra Schutzfolien um das Aroma zu bewahren."},"aioseo_meta_data":{"post_id":"20215757","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-03 15:34:56","updated":"2026-04-21 18:13:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/javataste.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/javataste.de\/en\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/\" title=\"Getr\u00e4nke\">Getr\u00e4nke<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPoci Teh Melati \u2014 indonesischer Jasmintee 25x2g\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/javataste.de\/en"},{"label":"Shop","link":"https:\/\/javataste.de\/en\/shop\/"},{"label":"Getr\u00e4nke","link":"https:\/\/javataste.de\/en\/produkt-kategorie\/getraenke\/"},{"label":"Poci Teh Melati \u2014 indonesischer Jasmintee 25x2g","link":"https:\/\/javataste.de\/en\/product\/poci-teh-melati-indonesischer-jasmintee-25x2g\/"}],"_links":{"self":[{"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/product\/20215757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/comments?post=20215757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/media\/20215758"}],"wp:attachment":[{"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/media?parent=20215757"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/product_brand?post=20215757"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/product_cat?post=20215757"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/javataste.de\/en\/wp-json\/wp\/v2\/product_tag?post=20215757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}